{"id":10925,"date":"2020-10-26T08:37:00","date_gmt":"2020-10-26T07:37:00","guid":{"rendered":"https:\/\/www.neva.eu\/non-classifiee\/lautomatisation-des-stores-a-lamelles-exterieurs-quel-en-est-le-fonctionnement-et-comment-choisir\/"},"modified":"2023-01-23T15:00:36","modified_gmt":"2023-01-23T14:00:36","slug":"lautomatisation-des-stores-a-lamelles-exterieurs-quel-en-est-le-fonctionnement-et-comment-choisir","status":"publish","type":"post","link":"https:\/\/www.neva.eu\/fr\/conseils-et-manuels\/lautomatisation-des-stores-a-lamelles-exterieurs-quel-en-est-le-fonctionnement-et-comment-choisir\/","title":{"rendered":"L\u2019automatisation des stores \u00e0 lamelles ext\u00e9rieurs : quel en est le fonctionnement et comment choisir\u00a0?"},"content":{"rendered":"        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Si vous n\u2019avez aucune envie de commander votre store manuellement avec une manivelle ou un cordon, choisissez un mod\u00e8le avec \u00e9lectromoteur. Un tel store est ensuite raccord\u00e9 \u00e0&nbsp;une commande \u00e0&nbsp;distance et peut donc simplement \u00eatre command\u00e9 depuis votre canap\u00e9 ou votre lit. Ceci ne constitue pas encore un syst\u00e8me de domotique car votre t\u00e9l\u00e9commande ne sert alors qu\u2019\u00e0 commander votre store. En plus, votre commande \u00e0&nbsp;distance ne fonctionnera plus si vous quittez votre maison.&nbsp;<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Pour une automatisation totale de vos stores, optez pour un <strong>syst\u00e8me de domotique<\/strong>. Celui-ci vous permettra de toujours garder le contr\u00f4le de tous les \u00e9l\u00e9ments importants de votre maison. En plus de vos stores, vous pouvez aussi y&nbsp;connecter la porte de votre garage, votre syst\u00e8me d\u2019alarme, vos radiateurs, le syst\u00e8me d\u2019arrosage de votre jardin ou encore les serrures de s\u00e9curit\u00e9. L\u2019ensemble est connect\u00e9 \u00e0&nbsp;un seul et unique bo\u00eetier de commande et peut \u00eatre command\u00e9 depuis votre smartphone, votre tablette ou votre ordinateur, o\u00f9 que vous soyez, au travail comme en vacances.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-heading typography my-1\">\n              \n<h2 class=\"wp-block-heading\">Un syst\u00e8me de domotique doit \u00eatre pr\u00e9vu d\u00e8s la phase de projet<\/h2>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Les <strong>syst\u00e8mes de domotique les plus courants fonctionnent via des c\u00e2bles<\/strong> qui permettent de transf\u00e9rer les commandes jusqu\u2019aux appareils et \u00e9l\u00e9ments de votre int\u00e9rieur que vous souhaitez contr\u00f4ler, comme par exemple vos stores. Si vous construisez ou r\u00e9novez totalement votre maison, pensez donc \u00e0&nbsp;la domotique d\u00e8s la phase de projet. Vous \u00e9viterez ensuite de devoir \u00e0&nbsp;nouveau intervenir dans les murs pour installer le c\u00e2blage.&nbsp;<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Si vous souhaitez int\u00e9grer un tel syst\u00e8me alors que votre maison est d\u00e9j\u00e0 termin\u00e9e, pr\u00e9parez-vous \u00e0&nbsp;intervenir dans les murs pour pouvoir passer le c\u00e2blage depuis le moteur \u00e9lectrique de vos stores \u00e0&nbsp;lamelles ext\u00e9rieurs vers le bo\u00eetier de commande. Ce bo\u00eetier est en effet g\u00e9n\u00e9ralement fixe et il ne peut donc pas \u00eatre install\u00e9 ou d\u00e9plac\u00e9 sans intervention dans le&nbsp;mur.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-heading typography my-1\">\n              \n<h2 class=\"wp-block-heading\">Le syst\u00e8me Somfy TaHoma peut \u00eatre install\u00e9 apr\u00e8s les stores et sans c\u00e2blage<\/h2>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Il existe aussi des syst\u00e8mes encore plus sophistiqu\u00e9s qui peuvent \u00eatre install\u00e9s sans aucun travaux de ma\u00e7onnerie et d\u2019\u00e9lectricit\u00e9. <strong>Ceux-ci sont bas\u00e9s sur une technologie sans fil<\/strong>. Vous pouvez alors commander vos stores et vos autres \u00e9quipements d\u2019o\u00f9 que vous soyez, \u00e0&nbsp;la seule condition d\u2019avoir acc\u00e8s \u00e0&nbsp;internet.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-heading typography my-1\">\n              \n<h3 class=\"wp-block-heading\"><strong>Comment un tel syst\u00e8me fonctionne-t-il dans la pratique&nbsp;?<\/strong><\/h3>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Il vous suffit d\u2019avoir des stores \u00e0&nbsp;lamelles ext\u00e9rieurs avec moteur radio et d\u2019acheter un syst\u00e8me de domotique <a href=\"https:\/\/www.neva.eu\/fr\/smart-home\/produits\/somfy-tahoma\/\" title=\"Somfy TaHoma\">Somfy TaHoma<\/a>. Celui-ci ressemble \u00e0&nbsp;un modem, c\u2019est-\u00e0-dire que <strong>c\u2019est un bo\u00eetier que vous connectez \u00e0&nbsp;une prise et \u00e0&nbsp;un routeur<\/strong>. Vous t\u00e9l\u00e9chargez ensuite une application, vous vous enregistrez et quelques clics suffisent ensuite pour appairer tous les moteurs de votre maison. Vous pouvez ainsi tout r\u00e9gler seul. Tout est tr\u00e8s facile et n\u2019exige pas l\u2019intervention d\u2019un professionnel.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-image typography my-1\">\n              \n<figure class=\"wp-block-image size-large is-style-default advgb-dyn-c509c2cc\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"960\" src=\"https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-1.jpg\" alt class=\"wp-image-10784\" srcset=\"https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-1.jpg 1920w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-1-1536x768.jpg 1536w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-1-1280x640.jpg 1280w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-1-940x470.jpg 940w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-1-758x379.jpg 758w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-1-425x213.jpg 425w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Si vous choisissez un syst\u00e8me de domotique sans fil, vous n\u2019avez aucun travail de pr\u00e9paration. Il vous suffit de connecter votre bo\u00eetier au r\u00e9seau et au routeur. Ce syst\u00e8me est donc parfait \u00e0&nbsp;installer dans une maison d\u00e9j\u00e0 habit\u00e9e.<\/figcaption><\/figure>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p><strong>Une seule application vous sert ensuite \u00e0&nbsp;contr\u00f4ler l\u2019ensemble de votre maison, m\u00eame \u00e0&nbsp;distance<\/strong>. Vous pouvez ainsi par exemple d\u00e9cider d\u2019ouvrir les stores de votre maison au moment o\u00f9 vous quittez votre travail pour \u00eatre s\u00fbr de profiter de la chaleur des rayons du soleil dans votre salon d\u00e8s votre retour.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Vous disposez \u00e9galement d\u2019une petite t\u00e9l\u00e9commande qui fonctionne avec une pile. Vous pouvez donc l\u2019installer n\u2019importe o\u00f9 dans votre maison.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>\u00ab&nbsp;Ces syst\u00e8mes de domotique n\u2019exigeant aucun c\u00e2blage, vous pouvez par exemple fixer la commande sur le bord de votre lit. Personnellement, c\u2019est de l\u00e0 que je commande mes stores et la lumi\u00e8re qui p\u00e9n\u00e8tre lorsque je vais me coucher, puis le matin au petit r\u00e9veil. L\u2019installation est aussi possible sur un mur. Sa pose est tellement facile que vous pouvez \u00e0&nbsp;tout moment changer l\u2019am\u00e9nagement de votre maison et d\u00e9placer votre bo\u00eetier, sans aucun travaux,&nbsp;\u00bb d\u00e9crit le manager produit de Somfy Jan Hrn\u010d\u00ed\u0159.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p><strong>Jusqu\u2019\u00e0 200 appareils et \u00e9l\u00e9ments<\/strong> peuvent \u00eatre connect\u00e9s au syst\u00e8me TaHoma qui suffit donc largement quelle que soit la dimension de la maison. En plus, les stores sont consid\u00e9r\u00e9s comme un seul \u00e9l\u00e9ment, m\u00eame si vous en avez par exemple sur 10 fen\u00eatres.<\/p>\n      <\/section>\n\n\n        <section id=\"component-e236c7a8cd38cbadf6137bafc83acc43\" class=\"component component-tip-background tip-background\">\n              <svg width=\"100%\" height=\"100%\" viewBox=\"0 0 100 100\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-miterlimit:2;\">\n    <g transform=\"matrix(4.16667,0,0,4.16667,0,0)\">\n      <path d=\"M12.704,19.927L11.296,19.927L11.296,20.374L12.704,20.374L12.704,19.927ZM13.248,12.243L13.248,11.408C13.248,11.317 13.32,11.245 13.408,11.245C13.497,11.245 13.57,11.317 13.57,11.408L13.57,17.114L14.001,17.114C14.177,17.114 14.338,17.04 14.455,16.924C14.572,16.808 14.643,16.648 14.643,16.47L14.643,15.13C14.643,15.083 14.665,15.037 14.705,15.004C15.212,14.6 15.627,14.082 15.912,13.493C16.185,12.923 16.339,12.286 16.339,11.611C16.339,10.413 15.853,9.328 15.069,8.542C14.283,7.756 13.199,7.271 12,7.271C10.801,7.271 9.716,7.756 8.931,8.542C8.146,9.328 7.66,10.413 7.66,11.611C7.66,12.286 7.814,12.923 8.087,13.493C8.371,14.08 8.784,14.594 9.289,14.998C9.329,15.029 9.355,15.077 9.355,15.13L9.355,16.47C9.355,16.648 9.428,16.808 9.543,16.924L9.545,16.925C9.662,17.041 9.821,17.114 9.999,17.114L10.43,17.114L10.43,11.408C10.43,11.317 10.502,11.245 10.591,11.245C10.68,11.245 10.752,11.317 10.752,11.408L10.752,12.243L11.839,12.243L11.839,11.408C11.839,11.317 11.912,11.245 12,11.245C12.088,11.245 12.161,11.317 12.161,11.408L12.161,12.243L13.248,12.243ZM13.248,17.114L13.248,12.563L12.161,12.563L12.161,13.401C12.161,13.489 12.088,13.56 12,13.56C11.912,13.56 11.839,13.489 11.839,13.401L11.839,12.563L10.752,12.563L10.752,17.114L13.248,17.114ZM14.039,18.703L9.96,18.703L9.96,18.962C9.96,19.14 10.034,19.3 10.149,19.416L10.15,19.417C10.267,19.535 10.428,19.606 10.605,19.606L13.394,19.606C13.573,19.606 13.733,19.535 13.848,19.416C13.965,19.3 14.039,19.139 14.039,18.962L14.039,18.703ZM9.96,18.379L14.039,18.379L14.039,17.435L9.96,17.435L9.96,18.379ZM12.161,5.337C12.161,5.425 12.088,5.498 12,5.498C11.912,5.498 11.839,5.425 11.839,5.337L11.839,3.465C11.839,3.377 11.912,3.305 12,3.305C12.088,3.305 12.161,3.377 12.161,3.465L12.161,5.337ZM18.274,11.772C18.184,11.772 18.112,11.701 18.112,11.61C18.112,11.522 18.184,11.451 18.274,11.451L20.144,11.451C20.235,11.451 20.305,11.522 20.305,11.61C20.305,11.701 20.235,11.772 20.144,11.772L18.274,11.772ZM5.727,11.451C5.815,11.451 5.887,11.522 5.887,11.61C5.887,11.701 5.815,11.772 5.727,11.772L3.854,11.772C3.765,11.772 3.693,11.701 3.693,11.61C3.693,11.522 3.765,11.451 3.854,11.451L5.727,11.451ZM16.549,7.288L17.873,5.964C17.935,5.903 17.935,5.8 17.873,5.738C17.81,5.674 17.709,5.674 17.646,5.738L16.322,7.062C16.26,7.124 16.26,7.227 16.322,7.288C16.385,7.352 16.487,7.352 16.549,7.288ZM7.678,7.062L6.354,5.738C6.291,5.674 6.188,5.674 6.126,5.738C6.063,5.8 6.063,5.903 6.126,5.964L7.45,7.288C7.512,7.352 7.615,7.352 7.678,7.288C7.74,7.227 7.74,7.124 7.678,7.062ZM12,6.951C13.287,6.951 14.453,7.472 15.296,8.315C16.138,9.16 16.661,10.325 16.661,11.611C16.661,12.333 16.496,13.019 16.201,13.631C15.907,14.243 15.483,14.78 14.964,15.207L14.964,16.47C14.964,16.736 14.857,16.977 14.682,17.153C14.59,17.244 14.482,17.317 14.36,17.367L14.36,18.962C14.36,19.228 14.252,19.469 14.077,19.644C13.903,19.82 13.661,19.927 13.394,19.927L13.026,19.927L13.026,20.536C13.026,20.623 12.954,20.697 12.865,20.697L11.136,20.697C11.046,20.697 10.975,20.623 10.975,20.536L10.975,19.927L10.605,19.927C10.339,19.927 10.099,19.82 9.923,19.644L9.922,19.644L9.921,19.642C9.748,19.467 9.64,19.226 9.64,18.962L9.64,17.366C9.519,17.317 9.409,17.244 9.317,17.153L9.317,17.152L9.315,17.151C9.142,16.974 9.034,16.736 9.034,16.47L9.034,15.207C8.517,14.78 8.094,14.243 7.798,13.631C7.503,13.019 7.338,12.333 7.338,11.611C7.338,10.325 7.86,9.16 8.704,8.315C9.547,7.472 10.713,6.951 12,6.951Z\" style=\"fill:rgb(12,178,214);fill-rule:nonzero;\"\/>\n      <path d=\"M12.704,19.927L11.296,19.927L11.296,20.374L12.704,20.374L12.704,19.927ZM13.248,12.243L13.248,11.408C13.248,11.317 13.32,11.245 13.408,11.245C13.497,11.245 13.57,11.317 13.57,11.408L13.57,17.114L14.001,17.114C14.177,17.114 14.338,17.04 14.455,16.924C14.572,16.808 14.643,16.648 14.643,16.47L14.643,15.13C14.643,15.083 14.665,15.037 14.705,15.004C15.212,14.6 15.627,14.082 15.912,13.493C16.185,12.923 16.339,12.286 16.339,11.611C16.339,10.413 15.853,9.328 15.069,8.542C14.283,7.756 13.199,7.271 12,7.271C10.801,7.271 9.716,7.756 8.931,8.542C8.146,9.328 7.66,10.413 7.66,11.611C7.66,12.286 7.814,12.923 8.087,13.493C8.371,14.08 8.784,14.594 9.289,14.998C9.329,15.029 9.355,15.077 9.355,15.13L9.355,16.47C9.355,16.648 9.428,16.808 9.543,16.924L9.545,16.925C9.662,17.041 9.821,17.114 9.999,17.114L10.43,17.114L10.43,11.408C10.43,11.317 10.502,11.245 10.591,11.245C10.68,11.245 10.752,11.317 10.752,11.408L10.752,12.243L11.839,12.243L11.839,11.408C11.839,11.317 11.912,11.245 12,11.245C12.088,11.245 12.161,11.317 12.161,11.408L12.161,12.243L13.248,12.243ZM13.248,17.114L13.248,12.563L12.161,12.563L12.161,13.401C12.161,13.489 12.088,13.56 12,13.56C11.912,13.56 11.839,13.489 11.839,13.401L11.839,12.563L10.752,12.563L10.752,17.114L13.248,17.114ZM14.039,18.703L9.96,18.703L9.96,18.962C9.96,19.14 10.034,19.3 10.149,19.416L10.15,19.417C10.267,19.535 10.428,19.606 10.605,19.606L13.394,19.606C13.573,19.606 13.733,19.535 13.848,19.416C13.965,19.3 14.039,19.139 14.039,18.962L14.039,18.703ZM9.96,18.379L14.039,18.379L14.039,17.435L9.96,17.435L9.96,18.379ZM12.161,5.337C12.161,5.425 12.088,5.498 12,5.498C11.912,5.498 11.839,5.425 11.839,5.337L11.839,3.465C11.839,3.377 11.912,3.305 12,3.305C12.088,3.305 12.161,3.377 12.161,3.465L12.161,5.337ZM18.274,11.772C18.184,11.772 18.112,11.701 18.112,11.61C18.112,11.522 18.184,11.451 18.274,11.451L20.144,11.451C20.235,11.451 20.305,11.522 20.305,11.61C20.305,11.701 20.235,11.772 20.144,11.772L18.274,11.772ZM5.727,11.451C5.815,11.451 5.887,11.522 5.887,11.61C5.887,11.701 5.815,11.772 5.727,11.772L3.854,11.772C3.765,11.772 3.693,11.701 3.693,11.61C3.693,11.522 3.765,11.451 3.854,11.451L5.727,11.451ZM16.549,7.288L17.873,5.964C17.935,5.903 17.935,5.8 17.873,5.738C17.81,5.674 17.709,5.674 17.646,5.738L16.322,7.062C16.26,7.124 16.26,7.227 16.322,7.288C16.385,7.352 16.487,7.352 16.549,7.288ZM7.678,7.062L6.354,5.738C6.291,5.674 6.188,5.674 6.126,5.738C6.063,5.8 6.063,5.903 6.126,5.964L7.45,7.288C7.512,7.352 7.615,7.352 7.678,7.288C7.74,7.227 7.74,7.124 7.678,7.062ZM12,6.951C13.287,6.951 14.453,7.472 15.296,8.315C16.138,9.16 16.661,10.325 16.661,11.611C16.661,12.333 16.496,13.019 16.201,13.631C15.907,14.243 15.483,14.78 14.964,15.207L14.964,16.47C14.964,16.736 14.857,16.977 14.682,17.153C14.59,17.244 14.482,17.317 14.36,17.367L14.36,18.962C14.36,19.228 14.252,19.469 14.077,19.644C13.903,19.82 13.661,19.927 13.394,19.927L13.026,19.927L13.026,20.536C13.026,20.623 12.954,20.697 12.865,20.697L11.136,20.697C11.046,20.697 10.975,20.623 10.975,20.536L10.975,19.927L10.605,19.927C10.339,19.927 10.099,19.82 9.923,19.644L9.922,19.644L9.921,19.642C9.748,19.467 9.64,19.226 9.64,18.962L9.64,17.366C9.519,17.317 9.409,17.244 9.317,17.153L9.317,17.152L9.315,17.151C9.142,16.974 9.034,16.736 9.034,16.47L9.034,15.207C8.517,14.78 8.094,14.243 7.798,13.631C7.503,13.019 7.338,12.333 7.338,11.611C7.338,10.325 7.86,9.16 8.704,8.315C9.547,7.472 10.713,6.951 12,6.951Z\" style=\"fill:none;stroke:rgb(12,178,214);stroke-width:0.1px;\"\/>\n    <\/g>\n  <\/svg>\n  <p>Si vous vous appr\u00eatez \u00e0&nbsp;choisir un syst\u00e8me de domotique, questionnez tout d\u2019abord le fabricant sur les marques de moteurs et sur les \u00e9l\u00e9ments de votre maison qui peuvent y&nbsp;\u00eatre raccord\u00e9s.&nbsp;<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p><\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-heading typography my-1\">\n              \n<h2 class=\"wp-block-heading\">Si vous avez un syst\u00e8me de domotique, cr\u00e9ez vos propres sc\u00e9narios<\/h2>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Les syst\u00e8mes de domotique permettent de <strong>cr\u00e9er des sc\u00e9narios intelligents<\/strong>. Par exemple, lorsque vous quittez votre garage en voiture, votre garage peut se refermer, les lumi\u00e8res de votre maison peuvent s\u2019\u00e9teindre et l\u2019alarme s\u2019activer. Et vous pouvez aussi int\u00e9grer la commande de vos stores.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Leur commande peut \u00eatre optimis\u00e9e avec des <strong>capteurs de soleil ou de vent<\/strong>. Lorsque le soleil brille fortement en \u00e9t\u00e9, vos stores se refermeront automatiquement pour \u00e9viter \u00e0&nbsp;votre int\u00e9rieur de trop monter en temp\u00e9rature. S\u2019il y&nbsp;a trop de vent, les lames de vos stores remonteront automatiquement pour \u00e9viter de s\u2019endommager. Ce type de capteurs fonctionne sans \u00eatre raccord\u00e9 \u00e0&nbsp;un syst\u00e8me de domotique, mais un tel syst\u00e8me vous permet d\u2019envoyer des instructions plus compliqu\u00e9es \u00e0&nbsp;vos stores. Vous pouvez aussi d\u00e9cider quel store doit r\u00e9agir \u00e0&nbsp;quelles instructions.&nbsp;<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Monsieur Hrn\u010d\u00ed\u0159 nous apporte encore plus de pr\u00e9cisions sur les possibilit\u00e9s propos\u00e9es : \u00ab&nbsp;Les sc\u00e9narios peuvent aussi \u00eatre r\u00e9gl\u00e9s selon un calendrier. L\u2019application vous permet de facilement saisir les instructions en fonction de vos habitudes et, par exemple, de diff\u00e9rencier les jours de la semaine et les jours du week-end. Vos stores peuvent ainsi se relever le matin \u00e0&nbsp;6 heures lorsque vous allez au travail ou bien se refermer chaque jour une heure avant le coucher du soleil.&nbsp;\u00bb<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Vous pouvez aussi sans aucune difficult\u00e9 raccorder un store toile \u00e0&nbsp;votre syst\u00e8me Somfy.<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-image typography my-1\">\n              \n<figure class=\"wp-block-image size-large is-style-default advgb-dyn-d0b3083b\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"960\" src=\"https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-2.jpg\" alt class=\"wp-image-10790\" srcset=\"https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-2.jpg 1920w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-2-1536x768.jpg 1536w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-2-1280x640.jpg 1280w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-2-940x470.jpg 940w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-2-758x379.jpg 758w, https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii-2-425x213.jpg 425w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Si vous n\u2019avez pas besoin d\u2019un syst\u00e8me de domotique qui contr\u00f4le toute votre maison et qu\u2019un syst\u00e8me de commande de vos stores vous suffit, optez pour le syst\u00e8me Connexoon de Somfy qui a&nbsp;\u00e9t\u00e9 pr\u00e9vu pour un nombre d\u2019\u00e9l\u00e9ments plus r\u00e9duits. Vous ne pourrez pas cr\u00e9er de sc\u00e9narios tr\u00e8s compliqu\u00e9s mais ce syst\u00e8me est r\u00e9ellement suffisant pour les stores.<\/figcaption><\/figure>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-heading typography my-1\">\n              \n<h2 class=\"wp-block-heading\">Avantages d\u2019un syst\u00e8me de domotique pour commander vos stores<\/h2>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Gr\u00e2ce \u00e0&nbsp;un syst\u00e8me de domotique, vous garderez le contr\u00f4le de l\u2019ensemble de votre maison, m\u00eame lorsque vous n\u2019y \u00eates pas. De&nbsp;plus&nbsp;:<\/p>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-list typography my-1\">\n              \n<ul class=\"wp-block-list\">\n<li><strong>Vous \u00e9conomisez du temps<\/strong>. Le syst\u00e8me est r\u00e9gl\u00e9 une fois et vos stores \u00e0&nbsp;lamelles ext\u00e9rieurs se referment et s\u2019inclinent ensuite automatiquement selon le sc\u00e9nario r\u00e9gl\u00e9.<\/li>\n\n\n\n<li><strong>Vous \u00e9conomisez de l\u2019\u00e9nergie<\/strong>. Votre maison intelligente g\u00e8re votre consommation selon vos besoins. Vous ne laissez donc pas inutilement passer les rayons du soleil lorsque cela est inutile ou pourrait provoquer une d\u00e9sagr\u00e9able augmentation de la chaleur dans votre int\u00e9rieur. Pendant l\u2019hiver, vous profitez au contraire d\u2019une plus grande luminosit\u00e9 de votre int\u00e9rieur.<\/li>\n\n\n\n<li><strong>Vous gagnez en s\u00e9curit\u00e9<\/strong>. Les stores \u00e0&nbsp;lamelles ext\u00e9rieurs automatis\u00e9s donnent l\u2019impression que vous \u00eates chez vous m\u00eame lorsque vous \u00eates en r\u00e9alit\u00e9 en vacances. Il vous suffit de r\u00e9gler un sc\u00e9nario selon lequel vos stores s\u2019ouvriront et se refermeront plusieurs fois par jour. Un tel syst\u00e8me combin\u00e9 \u00e0&nbsp;un \u00e9clairage automatique cr\u00e9era l\u2019illusion que vous \u00eates \u00e0&nbsp;la maison.<\/li>\n<\/ul>\n      <\/section>\n\n\n        <section class=\"component component-gutenberg-paragraph typography my-1\">\n              \n<p>Si vous envisagez un syst\u00e8me de domotique, prenez directement contact avec <a href=\"https:\/\/www.neva.eu\/fr\/trouver-un-revendeur\/\" title=\"nos partenaires\">nos partenaires<\/a>. Somfy dispose par exemple d\u2019un <a href=\"https:\/\/www.somfy.cz\/prodejni-mista\/somfy-experience-centrum\" title=\"showroom \">showroom <\/a>o\u00f9 vous pourrez facilement essayer diff\u00e9rents syst\u00e8me de domotique et ainsi trouver celui qui vous conviendra le&nbsp;mieux.<\/p>\n      <\/section>\n","protected":false},"excerpt":{"rendered":"<p>Connecter vos stores \u00e0 lamelles ext\u00e9rieurs au syst\u00e8me de domotique de votre maison vous permet de gagner du temps et de l\u2019\u00e9nergie. Il existe d\u2019ailleurs des syst\u00e8mes qui n\u2019exigent aucun travaux et qui peuvent \u00eatre install\u00e9s tout simplement, en quelques minutes. Lisez cet article pour conna\u00eetre toutes les possibilit\u00e9s propos\u00e9es par une commande intelligente de vos stores et d\u00e9couvrir comment fonctionne ce syst\u00e8me.<\/p>\n","protected":false},"author":4,"featured_media":10780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_daim_seo_power":"1000","_daim_enable_ail":"1","footnotes":""},"categories":[199],"tags":[],"class_list":["post-10925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseils-et-manuels"],"acf":[],"aioseo_notices":[],"author_meta":{"display_name":"Miloslav Matou\u0161ek","author_link":"https:\/\/www.neva.eu\/fr\/author\/matousek\/"},"featured_img":"https:\/\/www.neva.eu\/wp-content\/uploads\/neva-chytre-ovladani-venkovnich-zaluzii.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.neva.eu\/fr\/actualites\/categorie\/conseils-et-manuels\/\" class=\"advgb-post-tax-term\">Conseils et manuels<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Conseils et manuels<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 6 years il y a","modified":"Mis \u00e0 jour 3 years il y a"},"absolute_dates":{"created":"Publi\u00e9 le 26. 10. 2020","modified":"Mise \u00e0 jour le 23. 1. 2023"},"absolute_dates_time":{"created":"Publi\u00e9 le 26. 10. 2020 8:37","modified":"Mise \u00e0 jour le 23. 1. 2023 15:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/posts\/10925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/comments?post=10925"}],"version-history":[{"count":2,"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/posts\/10925\/revisions"}],"predecessor-version":[{"id":20843,"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/posts\/10925\/revisions\/20843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/media\/10780"}],"wp:attachment":[{"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/media?parent=10925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/categories?post=10925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.neva.eu\/fr\/wp-json\/wp\/v2\/tags?post=10925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}